{"id":7778,"date":"2026-01-27T07:04:43","date_gmt":"2026-01-27T06:04:43","guid":{"rendered":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/"},"modified":"2026-01-27T07:04:43","modified_gmt":"2026-01-27T06:04:43","slug":"quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl","status":"publish","type":"post","link":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/","title":{"rendered":"Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots &#8211; Seahawks en un Super Bowl"},"content":{"rendered":"<p>Este domingo qued\u00f3 definido el Super Bowl LX, sabemos ya que los New England Patriots han vuelto al Juego por el Campeonato de la NFL y su rival es un viejo conocido en estas instancias, los Seattle Seahawks que buscan una revancha que tiene 11 a\u00f1os cocin\u00e1ndose. El 1 de febrero de 2015 en el entonces llamado University of Phoenix Stadium de Glendale, Arizona, una intercepci\u00f3n improbable y ag\u00f3nica del entonces desconocido Malcolm Butler en la zona de anotaci\u00f3n le regal\u00f3 su cuarto Trofeo Vince Lombardi al ya para ese momento m\u00edtico quarterback Tom Brady y de paso romi\u00f3 cruelmente&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este domingo qued\u00f3 definido el Super Bowl LX, sabemos ya que los New England Patriots han vuelto al Juego por el Campeonato de la NFL y su rival es un viejo conocido en estas instancias, los Seattle Seahawks que buscan una revancha que tiene 11 a\u00f1os cocin\u00e1ndose. El 1 de febrero de 2015 en el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":7779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[62],"tags":[],"class_list":["post-7778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots - Seahawks en un Super Bowl - Senda Noticiosa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots - Seahawks en un Super Bowl - Senda Noticiosa\" \/>\n<meta property=\"og:description\" content=\"Este domingo qued\u00f3 definido el Super Bowl LX, sabemos ya que los New England Patriots han vuelto al Juego por el Campeonato de la NFL y su rival es un viejo conocido en estas instancias, los Seattle Seahawks que buscan una revancha que tiene 11 a\u00f1os cocin\u00e1ndose. El 1 de febrero de 2015 en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/\" \/>\n<meta property=\"og:site_name\" content=\"Senda Noticiosa\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-27T06:04:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots &#8211; Seahawks en un Super Bowl\",\"datePublished\":\"2026-01-27T06:04:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/\"},\"wordCount\":121,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/17694017349889.jpg\",\"articleSection\":[\"Deportes\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/\",\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/\",\"name\":\"Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots - Seahawks en un Super Bowl - Senda Noticiosa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/17694017349889.jpg\",\"datePublished\":\"2026-01-27T06:04:43+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/17694017349889.jpg\",\"contentUrl\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/17694017349889.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots - Seahawks en un Super Bowl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/01\\\/27\\\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sendanoticiosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots &#8211; Seahawks en un Super Bowl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/#website\",\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/\",\"name\":\"Senda Noticiosa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sendanoticiosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots - Seahawks en un Super Bowl - Senda Noticiosa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/","og_locale":"en_US","og_type":"article","og_title":"Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots - Seahawks en un Super Bowl - Senda Noticiosa","og_description":"Este domingo qued\u00f3 definido el Super Bowl LX, sabemos ya que los New England Patriots han vuelto al Juego por el Campeonato de la NFL y su rival es un viejo conocido en estas instancias, los Seattle Seahawks que buscan una revancha que tiene 11 a\u00f1os cocin\u00e1ndose. El 1 de febrero de 2015 en el [&hellip;]","og_url":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/","og_site_name":"Senda Noticiosa","article_published_time":"2026-01-27T06:04:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/#article","isPartOf":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/"},"author":{"name":"","@id":""},"headline":"Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots &#8211; Seahawks en un Super Bowl","datePublished":"2026-01-27T06:04:43+00:00","mainEntityOfPage":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/"},"wordCount":121,"commentCount":0,"image":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/#primaryimage"},"thumbnailUrl":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/01\/17694017349889.jpg","articleSection":["Deportes"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/","url":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/","name":"Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots - Seahawks en un Super Bowl - Senda Noticiosa","isPartOf":{"@id":"https:\/\/sendanoticiosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/#primaryimage"},"image":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/#primaryimage"},"thumbnailUrl":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/01\/17694017349889.jpg","datePublished":"2026-01-27T06:04:43+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/#primaryimage","url":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/01\/17694017349889.jpg","contentUrl":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/01\/17694017349889.jpg","width":1200,"height":800,"caption":"Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots - Seahawks en un Super Bowl"},{"@type":"BreadcrumbList","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/01\/27\/quien-fue-campeon-de-liga-mx-en-el-ultimo-patriots-seahawks-en-un-super-bowl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sendanoticiosa.com\/"},{"@type":"ListItem","position":2,"name":"Qui\u00e9n fue campe\u00f3n de Liga MX en el \u00faltimo Patriots &#8211; Seahawks en un Super Bowl"}]},{"@type":"WebSite","@id":"https:\/\/sendanoticiosa.com\/#website","url":"https:\/\/sendanoticiosa.com\/","name":"Senda Noticiosa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sendanoticiosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts\/7778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/comments?post=7778"}],"version-history":[{"count":0,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts\/7778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/media\/7779"}],"wp:attachment":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/media?parent=7778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/categories?post=7778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/tags?post=7778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}