{"id":7784,"date":"2026-02-01T06:58:41","date_gmt":"2026-02-01T05:58:41","guid":{"rendered":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/"},"modified":"2026-02-01T06:58:41","modified_gmt":"2026-02-01T05:58:41","slug":"dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas","status":"publish","type":"post","link":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/","title":{"rendered":"&#8220;Dos derrotas en los \u00faltimos 10 partidos&#8221;: Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas"},"content":{"rendered":"<p>Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas \/ ESPECIAL Los Pumas iniciaron el torneo con dudas por un empate contra Quer\u00e9taro por lo que la afici\u00f3n y analistas cuestionaban a Efra\u00edn Ju\u00e1rez por perder el ADN de la Universidad de jugar con canteranos. Sin embargo conforme ha avanzado el Clausura 2026, han demostrado mucha mejor\u00eda y se mantienen invictos. Sin embargo, para Efra\u00edn Ju\u00e1rez no se trata de ser el mejor o peor equipo por los resultados recientes, por lo que&#8230;<\/p>\n<p>Fuente: <a href=\"https:\/\/www.marca.com\/mx\/futbol\/liga-mx\/2026\/01\/31\/697d9eb322601d76278b4587.html\" target=\"_blank\" rel=\"nofollow noopener\">https:\/\/www.marca.com\/mx\/futbol\/liga-mx\/2026\/01\/31\/697d9eb322601d76278b4587.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas \/ ESPECIAL Los Pumas iniciaron el torneo con dudas por un empate contra Quer\u00e9taro por lo que la afici\u00f3n y analistas cuestionaban a Efra\u00edn Ju\u00e1rez por perder el ADN [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":7785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[62],"tags":[],"class_list":["post-7784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Dos derrotas en los \u00faltimos 10 partidos&quot;: Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas - Senda Noticiosa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Dos derrotas en los \u00faltimos 10 partidos&quot;: Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas - Senda Noticiosa\" \/>\n<meta property=\"og:description\" content=\"Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas \/ ESPECIAL Los Pumas iniciaron el torneo con dudas por un empate contra Quer\u00e9taro por lo que la afici\u00f3n y analistas cuestionaban a Efra\u00edn Ju\u00e1rez por perder el ADN [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/\" \/>\n<meta property=\"og:site_name\" content=\"Senda Noticiosa\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-01T05:58:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#8220;Dos derrotas en los \u00faltimos 10 partidos&#8221;: Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas\",\"datePublished\":\"2026-02-01T05:58:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/\"},\"wordCount\":149,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/17698402589569.jpg\",\"articleSection\":[\"Deportes\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/\",\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/\",\"name\":\"\\\"Dos derrotas en los \u00faltimos 10 partidos\\\": Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas - Senda Noticiosa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/17698402589569.jpg\",\"datePublished\":\"2026-02-01T05:58:41+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/17698402589569.jpg\",\"contentUrl\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/17698402589569.jpg\",\"width\":1200,\"height\":800,\"caption\":\"\\\"Dos derrotas en los \u00faltimos 10 partidos\\\": Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/01\\\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sendanoticiosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Dos derrotas en los \u00faltimos 10 partidos&#8221;: Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/#website\",\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/\",\"name\":\"Senda Noticiosa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sendanoticiosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Dos derrotas en los \u00faltimos 10 partidos\": Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas - Senda Noticiosa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/","og_locale":"en_US","og_type":"article","og_title":"\"Dos derrotas en los \u00faltimos 10 partidos\": Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas - Senda Noticiosa","og_description":"Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas \/ ESPECIAL Los Pumas iniciaron el torneo con dudas por un empate contra Quer\u00e9taro por lo que la afici\u00f3n y analistas cuestionaban a Efra\u00edn Ju\u00e1rez por perder el ADN [&hellip;]","og_url":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/","og_site_name":"Senda Noticiosa","article_published_time":"2026-02-01T05:58:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/#article","isPartOf":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/"},"author":{"name":"","@id":""},"headline":"&#8220;Dos derrotas en los \u00faltimos 10 partidos&#8221;: Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas","datePublished":"2026-02-01T05:58:41+00:00","mainEntityOfPage":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/"},"wordCount":149,"commentCount":0,"image":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/#primaryimage"},"thumbnailUrl":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/02\/17698402589569.jpg","articleSection":["Deportes"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/","url":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/","name":"\"Dos derrotas en los \u00faltimos 10 partidos\": Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas - Senda Noticiosa","isPartOf":{"@id":"https:\/\/sendanoticiosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/#primaryimage"},"image":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/#primaryimage"},"thumbnailUrl":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/02\/17698402589569.jpg","datePublished":"2026-02-01T05:58:41+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/#primaryimage","url":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/02\/17698402589569.jpg","contentUrl":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/02\/17698402589569.jpg","width":1200,"height":800,"caption":"\"Dos derrotas en los \u00faltimos 10 partidos\": Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas"},{"@type":"BreadcrumbList","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/01\/dos-derrotas-en-los-ultimos-10-partidos-efrain-juarez-pone-los-numeros-sobre-la-mesa-en-pumas-ante-las-criticas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sendanoticiosa.com\/"},{"@type":"ListItem","position":2,"name":"&#8220;Dos derrotas en los \u00faltimos 10 partidos&#8221;: Efra\u00edn Ju\u00e1rez pone los n\u00fameros sobre la mesa en Pumas ante las cr\u00edticas"}]},{"@type":"WebSite","@id":"https:\/\/sendanoticiosa.com\/#website","url":"https:\/\/sendanoticiosa.com\/","name":"Senda Noticiosa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sendanoticiosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts\/7784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/comments?post=7784"}],"version-history":[{"count":0,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts\/7784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/media\/7785"}],"wp:attachment":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/media?parent=7784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/categories?post=7784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/tags?post=7784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}