{"id":7794,"date":"2026-02-08T06:56:37","date_gmt":"2026-02-08T05:56:37","guid":{"rendered":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/"},"modified":"2026-02-08T06:56:37","modified_gmt":"2026-02-08T05:56:37","slug":"resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america","status":"publish","type":"post","link":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/","title":{"rendered":"Resumen y goles Mazatl\u00e1n vs Chivas: &#8216;Hormiga&#8217; Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica"},"content":{"rendered":"<p>Las Chivas han comenzado el Clausura 2026 de la mejor forma posible, cinco victorias en cinco partidos, paso perfecto que lo consolida en el primer lugar de la tabla general pase lo que pase en la jornada 5 del certamen. Este duelo entre Mazatl\u00e1n y Guadalajara se presentaba como un partido &#8216;sencillo&#8217; para el equipo de Milito, pues los Ca\u00f1oneros no hab\u00edan ganado en el torneo. Sin embargo, por momentos lleg\u00f3 a complicarse el panorama para las Chivas porque bajaron el ritmo del partido con la ventaja de dos goles y al recibir gol, tuvieron que apretar para as\u00ed llegar&#8230;<\/p>\n<p>Fuente: <a href=\"https:\/\/www.marca.com\/mx\/futbol\/liga-mx\/cronica\/2026\/02\/07\/6986c279e2704e5f258b456e.html\" target=\"_blank\" rel=\"nofollow noopener\">https:\/\/www.marca.com\/mx\/futbol\/liga-mx\/cronica\/2026\/02\/07\/6986c279e2704e5f258b456e.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Chivas han comenzado el Clausura 2026 de la mejor forma posible, cinco victorias en cinco partidos, paso perfecto que lo consolida en el primer lugar de la tabla general pase lo que pase en la jornada 5 del certamen. Este duelo entre Mazatl\u00e1n y Guadalajara se presentaba como un partido &#8216;sencillo&#8217; para el equipo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":7795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[62],"tags":[],"class_list":["post-7794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resumen y goles Mazatl\u00e1n vs Chivas: &#039;Hormiga&#039; Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica - Senda Noticiosa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumen y goles Mazatl\u00e1n vs Chivas: &#039;Hormiga&#039; Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica - Senda Noticiosa\" \/>\n<meta property=\"og:description\" content=\"Las Chivas han comenzado el Clausura 2026 de la mejor forma posible, cinco victorias en cinco partidos, paso perfecto que lo consolida en el primer lugar de la tabla general pase lo que pase en la jornada 5 del certamen. Este duelo entre Mazatl\u00e1n y Guadalajara se presentaba como un partido &#8216;sencillo&#8217; para el equipo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/\" \/>\n<meta property=\"og:site_name\" content=\"Senda Noticiosa\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-08T05:56:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Resumen y goles Mazatl\u00e1n vs Chivas: &#8216;Hormiga&#8217; Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica\",\"datePublished\":\"2026-02-08T05:56:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/\"},\"wordCount\":139,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/17704409708365.jpg\",\"articleSection\":[\"Deportes\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/\",\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/\",\"name\":\"Resumen y goles Mazatl\u00e1n vs Chivas: 'Hormiga' Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica - Senda Noticiosa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/17704409708365.jpg\",\"datePublished\":\"2026-02-08T05:56:37+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/17704409708365.jpg\",\"contentUrl\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/17704409708365.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Resumen y goles Mazatl\u00e1n vs Chivas: 'Hormiga' Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/02\\\/08\\\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sendanoticiosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumen y goles Mazatl\u00e1n vs Chivas: &#8216;Hormiga&#8217; Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/#website\",\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/\",\"name\":\"Senda Noticiosa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sendanoticiosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resumen y goles Mazatl\u00e1n vs Chivas: 'Hormiga' Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica - Senda Noticiosa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/","og_locale":"en_US","og_type":"article","og_title":"Resumen y goles Mazatl\u00e1n vs Chivas: 'Hormiga' Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica - Senda Noticiosa","og_description":"Las Chivas han comenzado el Clausura 2026 de la mejor forma posible, cinco victorias en cinco partidos, paso perfecto que lo consolida en el primer lugar de la tabla general pase lo que pase en la jornada 5 del certamen. Este duelo entre Mazatl\u00e1n y Guadalajara se presentaba como un partido &#8216;sencillo&#8217; para el equipo [&hellip;]","og_url":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/","og_site_name":"Senda Noticiosa","article_published_time":"2026-02-08T05:56:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/#article","isPartOf":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/"},"author":{"name":"","@id":""},"headline":"Resumen y goles Mazatl\u00e1n vs Chivas: &#8216;Hormiga&#8217; Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica","datePublished":"2026-02-08T05:56:37+00:00","mainEntityOfPage":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/"},"wordCount":139,"commentCount":0,"image":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/#primaryimage"},"thumbnailUrl":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/02\/17704409708365.jpg","articleSection":["Deportes"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/","url":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/","name":"Resumen y goles Mazatl\u00e1n vs Chivas: 'Hormiga' Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica - Senda Noticiosa","isPartOf":{"@id":"https:\/\/sendanoticiosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/#primaryimage"},"image":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/#primaryimage"},"thumbnailUrl":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/02\/17704409708365.jpg","datePublished":"2026-02-08T05:56:37+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/#primaryimage","url":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/02\/17704409708365.jpg","contentUrl":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/02\/17704409708365.jpg","width":1200,"height":800,"caption":"Resumen y goles Mazatl\u00e1n vs Chivas: 'Hormiga' Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica"},{"@type":"BreadcrumbList","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/02\/08\/resumen-y-goles-mazatlan-vs-chivas-hormiga-gonzalez-y-gabriel-milito-llegan-invictos-al-clasico-nacional-contra-america\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sendanoticiosa.com\/"},{"@type":"ListItem","position":2,"name":"Resumen y goles Mazatl\u00e1n vs Chivas: &#8216;Hormiga&#8217; Gonz\u00e1lez y Gabriel Milito llegan invictos al Cl\u00e1sico Nacional contra Am\u00e9rica"}]},{"@type":"WebSite","@id":"https:\/\/sendanoticiosa.com\/#website","url":"https:\/\/sendanoticiosa.com\/","name":"Senda Noticiosa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sendanoticiosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts\/7794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/comments?post=7794"}],"version-history":[{"count":0,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts\/7794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/media\/7795"}],"wp:attachment":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/media?parent=7794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/categories?post=7794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/tags?post=7794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}