{"id":8061,"date":"2026-05-12T20:26:45","date_gmt":"2026-05-12T18:26:45","guid":{"rendered":"https:\/\/sendanoticiosa.com\/?p=8061"},"modified":"2026-05-12T20:26:45","modified_gmt":"2026-05-12T18:26:45","slug":"segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas","status":"publish","type":"post","link":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/","title":{"rendered":"SEGOB afirma que M\u00e9xico fortalece cooperaci\u00f3n con la CIDH, para atender desapariciones de personas"},"content":{"rendered":"\n<p>La \u201cDesaparici\u00f3n de Personas\u201d como una \u201cPrioridad Nacional\u201d, donde todas las instituciones del Gobierno de M\u00e9xico cooperan para erradicar el delito y atender a las v\u00edctimas.<\/p>\n\n\n\n<p>El Subsecretario de Derechos Humanos, Poblaci\u00f3n y Migraci\u00f3n de la Secretar\u00eda de Gobernaci\u00f3n (SEGOB) Arturo Medina Padilla, aseguro que por instrucciones de la presidenta Claudia Sheinbaum Pardo, se atiende la \u201cDesaparici\u00f3n de Personas\u201d como una \u201cPrioridad Nacional\u201d, donde todas las instituciones del Gobierno de M\u00e9xico cooperan para erradicar el delito y atender a las v\u00edctimas.<\/p>\n\n\n\n<p>\u201cLas Reformas, mecanismos y acciones que hoy impulsa el Estado mexicano han sido construidas escuchando las voces de las v\u00edctimas y de sus familias, sus experiencias y sus exigencias\u201d<\/p>\n\n\n\n<p>Al participar en representaci\u00f3n del Gobierno de M\u00e9xico en el informe de la Comisi\u00f3n Interamericana de Derechos Humanos (CIDH) sobre desaparici\u00f3n de personas, Medina Padilla enfatiz\u00f3 que constituye un hecho de gran relevancia que muestra el compromiso con la cooperaci\u00f3n y el fortalecimiento del sistema multilateral.<\/p>\n\n\n\n<p>El funcionario dijo que se valora que la Comisi\u00f3n Interamericana de Derechos Humanos (CIDH) reconozca el enfoque de atenci\u00f3n a las causas, los avances en el fortalecimiento institucional, las Reformas construidas de la mano de las familias y las acciones en materia de b\u00fasqueda e identificaci\u00f3n humana.<\/p>\n\n\n\n<p>\u201cNos parece importante mencionar y agradecer, que la Comisi\u00f3n haya incorporado los comentarios, informaci\u00f3n y avances impulsados por el Estado mexicano durante la administraci\u00f3n\u201d<\/p>\n\n\n\n<p>Durante la presentaci\u00f3n, encabezada por la Comisionada y Relatora para M\u00e9xico de la CIDH, Andrea Pochak, se expuso la implementaci\u00f3n de la ruta de atenci\u00f3n trazada por la presidenta Claudia Sheinbaum Pardo, la cual pone a las familias al centro para dar mejores resultados.<\/p>\n\n\n\n<p>\u201cEntre los avances que ha generado esta ruta destaca la Reforma legislativa de 2025, construida de la mano de las familias, y la Estrategia Nacional de B\u00fasqueda de Personas Desaparecidas\u201d.<\/p>\n\n\n\n<p>Por su parte, el Subsecretario para Asuntos Multilaterales y Derechos Humanos de la Secretar\u00eda de Relaciones Exteriores, Enrique Ochoa Mart\u00ednez, destac\u00f3 que las soluciones m\u00e1s efectivas y duraderas se construyen en colaboraci\u00f3n con el Estado<\/p>\n\n\n\n<p>\u201cA trav\u00e9s de sus instituciones, en coordinaci\u00f3n con todos los \u00f3rdenes de gobierno y con la participaci\u00f3n activa de la sociedad civil\u201d.<\/p>\n\n\n\n<p>En la presentaci\u00f3n del Informe de la CIDH, participaron familias, colectivos de b\u00fasqueda de personas desaparecidas, representantes gubernamentales, agencias de Naciones Unidas, cuerpo diplom\u00e1tico en M\u00e9xico y organizaciones de la sociedad civil.<\/p>\n\n\n\n<p>Ambos representantes del Gobierno de M\u00e9xico coincidieron en que se continuar\u00e1 el di\u00e1logo constructivo y respetuoso que se ha establecido con la CIDH y ampliar\u00e1 los programas de cooperaci\u00f3n con agencias internacionales, en particular con la Oficina del Alto Comisionado de Naciones Unidas para los Derechos Humanos (OACNUDH) y el Fondo de Poblaci\u00f3n de Naciones Unidas (UNFPA), para as\u00ed continuar el fortalecimiento de nuestras capacidades institucionales y generar soluciones efectivas y duraderas.<\/p>\n\n\n\n<p>Entre las acciones del Estado mexicano que hoy operan destacan:<\/p>\n\n\n\n<p>1.La Alerta Nacional de B\u00fasqueda de Personas Desaparecidas.<br>2.La obligaci\u00f3n de abrir carpetas de investigaci\u00f3n ante el primer reporte de desaparici\u00f3n.<br>3.La creaci\u00f3n de la Base Nacional de Carpetas de Investigaci\u00f3n.<br>4.La creaci\u00f3n de la Plataforma \u00danica de Identidad.<br>5.La obligaci\u00f3n de que los estados cuenten con fiscal\u00edas especializadas y se creen unidades especializadas relacionadas con este delito.<br>6.El fortalecimiento del Banco Nacional de datos forenses.<br>7.El robustecimiento de la Comisi\u00f3n Nacional de B\u00fasqueda con la contrataci\u00f3n de especialistas y adquisici\u00f3n de equipamiento.<br>8.La obligaci\u00f3n de que todos los registros oficiales de personas desaparecidas cuenten con datos m\u00ednimos para identificar a las personas.<br>9.La garant\u00eda de la coordinaci\u00f3n entre las comisiones de b\u00fasqueda, las fiscal\u00edas estatales y la Fiscal\u00eda General de la Rep\u00fablica<br>10.La incorporaci\u00f3n de las comisiones estatales y nacional de v\u00edctimas, as\u00ed como otras instituciones en el Sistema Nacional de B\u00fasqueda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u201cDesaparici\u00f3n de Personas\u201d como una \u201cPrioridad Nacional\u201d, donde todas las instituciones del Gobierno de M\u00e9xico cooperan para erradicar el delito y atender a las v\u00edctimas. El Subsecretario de Derechos Humanos, Poblaci\u00f3n y Migraci\u00f3n de la Secretar\u00eda de Gobernaci\u00f3n (SEGOB) Arturo Medina Padilla, aseguro que por instrucciones de la presidenta Claudia Sheinbaum Pardo, se atiende [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[51],"tags":[],"class_list":["post-8061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SEGOB afirma que M\u00e9xico fortalece cooperaci\u00f3n con la CIDH, para atender desapariciones de personas - Senda Noticiosa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEGOB afirma que M\u00e9xico fortalece cooperaci\u00f3n con la CIDH, para atender desapariciones de personas - Senda Noticiosa\" \/>\n<meta property=\"og:description\" content=\"La \u201cDesaparici\u00f3n de Personas\u201d como una \u201cPrioridad Nacional\u201d, donde todas las instituciones del Gobierno de M\u00e9xico cooperan para erradicar el delito y atender a las v\u00edctimas. El Subsecretario de Derechos Humanos, Poblaci\u00f3n y Migraci\u00f3n de la Secretar\u00eda de Gobernaci\u00f3n (SEGOB) Arturo Medina Padilla, aseguro que por instrucciones de la presidenta Claudia Sheinbaum Pardo, se atiende [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/\" \/>\n<meta property=\"og:site_name\" content=\"Senda Noticiosa\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T18:26:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/05\/34.-SEGOB-afirma-que-Me.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"sendanoticom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sendanoticom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/\"},\"author\":{\"name\":\"sendanoticom\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/#\\\/schema\\\/person\\\/d8594fe19a3f804aa373a89f0b59c180\"},\"headline\":\"SEGOB afirma que M\u00e9xico fortalece cooperaci\u00f3n con la CIDH, para atender desapariciones de personas\",\"datePublished\":\"2026-05-12T18:26:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/\"},\"wordCount\":697,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/34.-SEGOB-afirma-que-Me.webp\",\"articleSection\":[\"Nacional\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/\",\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/\",\"name\":\"SEGOB afirma que M\u00e9xico fortalece cooperaci\u00f3n con la CIDH, para atender desapariciones de personas - Senda Noticiosa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/34.-SEGOB-afirma-que-Me.webp\",\"datePublished\":\"2026-05-12T18:26:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/#\\\/schema\\\/person\\\/d8594fe19a3f804aa373a89f0b59c180\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/34.-SEGOB-afirma-que-Me.webp\",\"contentUrl\":\"https:\\\/\\\/sendanoticiosa.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/34.-SEGOB-afirma-que-Me.webp\",\"width\":660,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/2026\\\/05\\\/12\\\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sendanoticiosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEGOB afirma que M\u00e9xico fortalece cooperaci\u00f3n con la CIDH, para atender desapariciones de personas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/#website\",\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/\",\"name\":\"Senda Noticiosa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sendanoticiosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sendanoticiosa.com\\\/#\\\/schema\\\/person\\\/d8594fe19a3f804aa373a89f0b59c180\",\"name\":\"sendanoticom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba34ef5c85a7337be858cab52ef8a3ec8e6226b79910ac1660585e274b4a4314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba34ef5c85a7337be858cab52ef8a3ec8e6226b79910ac1660585e274b4a4314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba34ef5c85a7337be858cab52ef8a3ec8e6226b79910ac1660585e274b4a4314?s=96&d=mm&r=g\",\"caption\":\"sendanoticom\"},\"sameAs\":[\"https:\\\/\\\/sendanoticiosa.com\"],\"url\":\"https:\\\/\\\/sendanoticiosa.com\\\/index.php\\\/author\\\/sendanoticom\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SEGOB afirma que M\u00e9xico fortalece cooperaci\u00f3n con la CIDH, para atender desapariciones de personas - Senda Noticiosa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/","og_locale":"en_US","og_type":"article","og_title":"SEGOB afirma que M\u00e9xico fortalece cooperaci\u00f3n con la CIDH, para atender desapariciones de personas - Senda Noticiosa","og_description":"La \u201cDesaparici\u00f3n de Personas\u201d como una \u201cPrioridad Nacional\u201d, donde todas las instituciones del Gobierno de M\u00e9xico cooperan para erradicar el delito y atender a las v\u00edctimas. El Subsecretario de Derechos Humanos, Poblaci\u00f3n y Migraci\u00f3n de la Secretar\u00eda de Gobernaci\u00f3n (SEGOB) Arturo Medina Padilla, aseguro que por instrucciones de la presidenta Claudia Sheinbaum Pardo, se atiende [&hellip;]","og_url":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/","og_site_name":"Senda Noticiosa","article_published_time":"2026-05-12T18:26:45+00:00","og_image":[{"width":660,"height":440,"url":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/05\/34.-SEGOB-afirma-que-Me.webp","type":"image\/webp"}],"author":"sendanoticom","twitter_card":"summary_large_image","twitter_misc":{"Written by":"sendanoticom","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/#article","isPartOf":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/"},"author":{"name":"sendanoticom","@id":"https:\/\/sendanoticiosa.com\/#\/schema\/person\/d8594fe19a3f804aa373a89f0b59c180"},"headline":"SEGOB afirma que M\u00e9xico fortalece cooperaci\u00f3n con la CIDH, para atender desapariciones de personas","datePublished":"2026-05-12T18:26:45+00:00","mainEntityOfPage":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/"},"wordCount":697,"commentCount":0,"image":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/#primaryimage"},"thumbnailUrl":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/05\/34.-SEGOB-afirma-que-Me.webp","articleSection":["Nacional"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/","url":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/","name":"SEGOB afirma que M\u00e9xico fortalece cooperaci\u00f3n con la CIDH, para atender desapariciones de personas - Senda Noticiosa","isPartOf":{"@id":"https:\/\/sendanoticiosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/#primaryimage"},"image":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/#primaryimage"},"thumbnailUrl":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/05\/34.-SEGOB-afirma-que-Me.webp","datePublished":"2026-05-12T18:26:45+00:00","author":{"@id":"https:\/\/sendanoticiosa.com\/#\/schema\/person\/d8594fe19a3f804aa373a89f0b59c180"},"breadcrumb":{"@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/#primaryimage","url":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/05\/34.-SEGOB-afirma-que-Me.webp","contentUrl":"https:\/\/sendanoticiosa.com\/wp-content\/uploads\/2026\/05\/34.-SEGOB-afirma-que-Me.webp","width":660,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/sendanoticiosa.com\/index.php\/2026\/05\/12\/segob-afirma-que-mexico-fortalece-cooperacion-con-la-cidh-para-atender-desapariciones-de-personas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sendanoticiosa.com\/"},{"@type":"ListItem","position":2,"name":"SEGOB afirma que M\u00e9xico fortalece cooperaci\u00f3n con la CIDH, para atender desapariciones de personas"}]},{"@type":"WebSite","@id":"https:\/\/sendanoticiosa.com\/#website","url":"https:\/\/sendanoticiosa.com\/","name":"Senda Noticiosa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sendanoticiosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sendanoticiosa.com\/#\/schema\/person\/d8594fe19a3f804aa373a89f0b59c180","name":"sendanoticom","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ba34ef5c85a7337be858cab52ef8a3ec8e6226b79910ac1660585e274b4a4314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba34ef5c85a7337be858cab52ef8a3ec8e6226b79910ac1660585e274b4a4314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba34ef5c85a7337be858cab52ef8a3ec8e6226b79910ac1660585e274b4a4314?s=96&d=mm&r=g","caption":"sendanoticom"},"sameAs":["https:\/\/sendanoticiosa.com"],"url":"https:\/\/sendanoticiosa.com\/index.php\/author\/sendanoticom\/"}]}},"_links":{"self":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts\/8061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/comments?post=8061"}],"version-history":[{"count":1,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts\/8061\/revisions"}],"predecessor-version":[{"id":8063,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/posts\/8061\/revisions\/8063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/media\/8062"}],"wp:attachment":[{"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/media?parent=8061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/categories?post=8061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sendanoticiosa.com\/index.php\/wp-json\/wp\/v2\/tags?post=8061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}